{"id":95470,"date":"2023-02-09T15:12:02","date_gmt":"2023-02-09T14:12:02","guid":{"rendered":"https:\/\/nextcloud.com\/blog\/come-installare-nextcloud-all-in-one-su-linux\/"},"modified":"2023-02-13T18:17:14","modified_gmt":"2023-02-13T17:17:14","slug":"come-installare-nextcloud-all-in-one-su-linux","status":"publish","type":"post","link":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/","title":{"rendered":"Come installare Nextcloud All-in-One su Linux"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sei un utente Linux che vuole installare l&#8217;immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti guidiamo attraverso i passaggi, proprio come abbiamo fatto nella nostra ultima <a href=\"https:\/\/nextcloud.com\/it\/blog\/la-tua-guida-a-nextcloud-all-in-one-su-windows-10-e-11\/\" target=\"_blank\" rel=\"noreferrer noopener\">guida AIO per Windows 10 e 11!<\/a> \ud83c\udf89<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud All-in-One \u00e8 un progetto basato su Docker che permette di installare un solo container che fa il lavoro pesante di creare e gestire tutti i container necessari per un&#8217;installazione completa di Nextcloud. Nextcloud AIO non solo offre una facile implementazione e manutenzione di molte delle funzioni Nextcloud incluse, ma puoi anche aspettarti un&#8217;interfaccia facile da usare, aggiornamenti senza stress e un approccio pi\u00f9 semplicistico per far funzionare la maggior parte delle funzioni out-of-the-box.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nextcloud AIO include:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nextcloud<\/li>\n\n\n\n<li>Nextcloud Office<\/li>\n\n\n\n<li>Backend ad alte prestazioni per Nextcloud Files<\/li>\n\n\n\n<li>Backend ad alte prestazioni per Nextcloud Talk<\/li>\n\n\n\n<li>Soluzione di backup (basata su <a href=\"https:\/\/github.com\/borgbackup\/borg#what-is-borgbackup\">BorgBackup)<\/a><\/li>\n\n\n\n<li>Imaginary (per le anteprime di heic, tiff e webp)<\/li>\n\n\n\n<li>ClamAV (backend antivirus per Nextcloud)<\/li>\n\n\n\n<li>Fulltextsearch<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>&#8220;Utilizzando Nextcloud All-in-One rispetto agli altri metodi di installazione, ho constatato che le prestazioni sono sostanzialmente migliori, soprattutto su un server d&#8217;ufficio.&#8221;<\/p><cite>&#8211; Brandon Hopkins (TechHut)<\/cite><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Continua a leggere per scoprire una guida chiara e facile da seguire, <strong>passo dopo<\/strong> passo, su come configurare con successo un AIO per un PC Linux.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Guida per AIO su Linux<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le seguenti istruzioni sono valide per un PC Linux (ad esempio con Ubuntu 22.04 LTS) con una CPU x64 con almeno 4GB di RAM e 2 core.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Affinch\u00e9 la guida funzioni correttamente, dovrai ottenere un dominio pubblico ed essere in grado di aprire le porte. Assicurati di non essere dietro a CGNAT perch\u00e9 non funzioner\u00e0 nemmeno con quello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inoltre, tieni presente che le istruzioni si riferiscono a una configurazione senza server web o reverse proxy (come Apache, Nginx, ecc.). Se vuoi eseguirlo dietro un server web o un reverse proxy, fai riferimento <a href=\"https:\/\/github.com\/nextcloud\/all-in-one\/blob\/main\/reverse-proxy.md\" target=\"_blank\" rel=\"noreferrer noopener\">qui.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"install-docker\">Install Docker<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Installa Docker sulla tua installazione Linux seguendo la <a href=\"https:\/\/docs.docker.com\/engine\/install\/#server.\" target=\"_blank\" rel=\"noreferrer noopener\">documentazione ufficiale.<\/a> Il modo pi\u00f9 semplice \u00e8 installarlo utilizzando <strong>lo script di convenienza:<\/strong><\/li>\n<\/ol>\n\n\n\n<pre class=\"wp-block-code\"><code>curl -fsSL get.docker.com | sudo sh<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">2. Se hai bisogno del supporto Ipv6, devi attivarlo seguendo la guida <a href=\"https:\/\/docs.docker.com\/config\/daemon\/ipv6\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Installare AIO<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">3. Ora apri il Terminale e avvia AIO con questo comando:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code># For x64 CPUs and without a web server or reverse proxy (like Apache, Nginx and else) already in place:\nsudo docker run \\\n--sig-proxy=false \\\n--name nextcloud-aio-mastercontainer \\\n--restart always \\\n--publish 80:80 \\\n--publish 8080:8080 \\\n--publish 8443:8443 \\\n--volume nextcloud_aio_mastercontainer:\/mnt\/docker-aio-config \\\n--volume \/var\/run\/docker.sock:\/var\/run\/docker.sock:ro \\\nnextcloud\/all-in-one:latest<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Nota: potresti essere interessato a modificare la datadir di Nextcloud per memorizzare i file in una posizione diversa dal volume docker predefinito. Consulta <a href=\"https:\/\/github.com\/nextcloud\/all-in-one#how-to-change-the-default-location-of-nextclouds-datadir\">questa documentazione<\/a> per sapere come fare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Successivamente, puoi aprire l&#8217;interfaccia AIO su <code>https:\/\/localhost:8080<\/code> o <code>https:\/\/the.servers.ip.address:8080<\/code> Devi accettare il certificato autofirmato, dopodich\u00e9 dovresti vedere questo:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png\" alt=\"Schermata di configurazione di Nextcloud AIO\" class=\"wp-image-94581\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In alternativa, se le porte 80 e 8443 sono aperte nel tuo firewall\/router e un dominio \u00e8 configurato per puntare al tuo server, puoi raggiungere l&#8217;interfaccia AIO con un certificato valido utilizzando <code>https:\/\/your-domain.com:8443<\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Clicca su &#8220;Apri il login di Nextcloud AIO&#8221; e incolla la tua password:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2.png\" alt=\"Schermata di login di Nextcloud AIO\" class=\"wp-image-94586\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_2-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">6. A questo punto, dovresti vedere l&#8217;interfaccia AIO:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3.png\" alt=\"Schermata dell'interfaccia di Nextcloud AIO\" class=\"wp-image-94591\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_3-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">7. Successivamente, inserisci il dominio pubblico che hai ottenuto prima di seguire questa guida. L&#8217;interfaccia dovrebbe aiutarti a capire quali sono i passaggi esatti. (Imposta il DDNS per il tuo dominio in modo che punti al tuo IP pubblico, inoltra almeno le porte 443\/tcp, 3478\/udp e 3478\/tcp al tuo computer Linux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8. Dopo averla configurata correttamente, dovrebbe permetterti di passare alla fase successiva in cui potrai configurare i componenti aggiuntivi opzionali desiderati e il fuso orario e cliccare su <strong>Avvia contenitori<\/strong> per scaricarli e avviarli.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4.png\"><img decoding=\"async\" width=\"1824\" height=\"2736\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4.png\" alt=\"Schermata dei componenti aggiuntivi opzionali di Nextcloud AIO\" class=\"wp-image-94597\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4.png 1824w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4-200x300.png 200w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4-384x576.png 384w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4-768x1152.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4-1024x1536.png 1024w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_4-1365x2048.png 1365w\" sizes=\"(max-width: 1824px) 100vw, 1824px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">9. A questo punto, dovresti vedere uno spinner che richieder\u00e0 un po&#8217; di tempo a seconda della tua velocit\u00e0 di internet ~ circa 10 minuti o pi\u00f9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5.png\" alt=\"Nextcloud AIO: spinner sullo schermo\" class=\"wp-image-94602\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_5-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">10. Quando tutti i container sono stati scaricati e avviati, vedrai questa schermata che mostra i container ancora in fase di avvio che eseguiranno la prima installazione per te:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6.png\" alt=\"La schermata di Nextcloud AIO mostra l'installazione dei container\" class=\"wp-image-94609\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_6-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">11. Quando tutto \u00e8 pronto, dovresti vedere questa schermata:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7.png\"><img decoding=\"async\" width=\"2736\" height=\"1824\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7.png\" alt=\"La schermata di Nextcloud AIO mostra che la configurazione \u00e8 stata completata\" class=\"wp-image-94615\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7.png 2736w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7-300x200.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7-864x576.png 864w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7-768x512.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7-1536x1024.png 1536w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux_7-2048x1365.png 2048w\" sizes=\"(max-width: 2736px) 100vw, 2736px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">12. Infine, puoi aprire la tua nuova istanza Nextcloud e accedere con le credenziali di amministrazione fornite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco fatto! Tutto \u00e8 pronto e pronto per la produzione! \u2728<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Messaggi simili:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/nextcloud.com\/it\/blog\/la-tua-guida-a-nextcloud-all-in-one-su-windows-10-e-11\/\" target=\"_blank\" rel=\"noreferrer noopener\">La tua guida a Nextcloud All-in-One su Windows 10 e 11!<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Questo manuale AIO \u00e8 stato creato dal <a href=\"https:\/\/nextcloud.com\/team\/\" target=\"_blank\" rel=\"noreferrer noopener\">membro del team<\/a> Simon.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sei un utente Linux che vuole installare l&#8217;immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti guidiamo attraverso i passaggi, proprio come abbiamo fatto nella nostra ultima guida AIO per Windows 10 e 11! \ud83c\udf89 Nextcloud All-in-One \u00e8 un progetto basato su Docker che permette di installare un solo container che fa il [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":94584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[234,233,260,1],"tags":[],"class_list":["post-95470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","category-comunita","category-generale","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come installare Nextcloud All-in-One su Linux - Nextcloud<\/title>\n<meta name=\"description\" content=\"Sei un utente Linux che vuole installare l&#039;immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come installare Nextcloud All-in-One su Linux - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Sei un utente Linux che vuole installare l&#039;immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T14:12:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T17:17:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2736\" \/>\n\t<meta property=\"og:image:height\" content=\"1824\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mikaela Schneider\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nextclouders\" \/>\n<meta name=\"twitter:site\" content=\"@nextclouders\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mikaela Schneider\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/\"},\"author\":{\"name\":\"Mikaela Schneider\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#\\\/schema\\\/person\\\/8b00c7d4313f1ecb465e6785204ffb4b\"},\"headline\":\"Come installare Nextcloud All-in-One su Linux\",\"datePublished\":\"2023-02-09T14:12:02+00:00\",\"dateModified\":\"2023-02-13T17:17:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/\"},\"wordCount\":639,\"publisher\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/AIO-Linux.png\",\"articleSection\":[\"Blog\",\"Comunit\u00e0\",\"generale\",\"Uncategorized\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/\",\"name\":\"Come installare Nextcloud All-in-One su Linux - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/AIO-Linux.png\",\"datePublished\":\"2023-02-09T14:12:02+00:00\",\"dateModified\":\"2023-02-13T17:17:14+00:00\",\"description\":\"Sei un utente Linux che vuole installare l'immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/AIO-Linux.png\",\"contentUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/AIO-Linux.png\",\"width\":2736,\"height\":1824},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/blog\\\/come-installare-nextcloud-all-in-one-su-linux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come installare Nextcloud All-in-One su Linux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nextclouders\\\/\",\"https:\\\/\\\/x.com\\\/nextclouders\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10827569\\\/\",\"https:\\\/\\\/youtube.com\\\/nextcloud\",\"https:\\\/\\\/www.instagram.com\\\/nextclouders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/it\\\/#\\\/schema\\\/person\\\/8b00c7d4313f1ecb465e6785204ffb4b\",\"name\":\"Mikaela Schneider\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g\",\"caption\":\"Mikaela Schneider\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come installare Nextcloud All-in-One su Linux - Nextcloud","description":"Sei un utente Linux che vuole installare l'immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Come installare Nextcloud All-in-One su Linux - Nextcloud","og_description":"Sei un utente Linux che vuole installare l'immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!","og_url":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2023-02-09T14:12:02+00:00","article_modified_time":"2023-02-13T17:17:14+00:00","og_image":[{"width":2736,"height":1824,"url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","type":"image\/png"}],"author":"Mikaela Schneider","twitter_card":"summary_large_image","twitter_creator":"@nextclouders","twitter_site":"@nextclouders","twitter_misc":{"Scritto da":"Mikaela Schneider","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#article","isPartOf":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/"},"author":{"name":"Mikaela Schneider","@id":"https:\/\/staging.nextcloud.com\/it\/#\/schema\/person\/8b00c7d4313f1ecb465e6785204ffb4b"},"headline":"Come installare Nextcloud All-in-One su Linux","datePublished":"2023-02-09T14:12:02+00:00","dateModified":"2023-02-13T17:17:14+00:00","mainEntityOfPage":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/"},"wordCount":639,"publisher":{"@id":"https:\/\/staging.nextcloud.com\/it\/#organization"},"image":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","articleSection":["Blog","Comunit\u00e0","generale","Uncategorized"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/","url":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/","name":"Come installare Nextcloud All-in-One su Linux - Nextcloud","isPartOf":{"@id":"https:\/\/staging.nextcloud.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#primaryimage"},"image":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","datePublished":"2023-02-09T14:12:02+00:00","dateModified":"2023-02-13T17:17:14+00:00","description":"Sei un utente Linux che vuole installare l'immagine Docker di Nextcloud All-in-One, o AIO? In questo blog ti spieghiamo come fare!","breadcrumb":{"@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#primaryimage","url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","contentUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","width":2736,"height":1824},{"@type":"BreadcrumbList","@id":"https:\/\/staging.nextcloud.com\/it\/blog\/come-installare-nextcloud-all-in-one-su-linux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.nextcloud.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come installare Nextcloud All-in-One su Linux"}]},{"@type":"WebSite","@id":"https:\/\/staging.nextcloud.com\/it\/#website","url":"https:\/\/staging.nextcloud.com\/it\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/staging.nextcloud.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.nextcloud.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/staging.nextcloud.com\/it\/#organization","name":"Nextcloud","url":"https:\/\/staging.nextcloud.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/staging.nextcloud.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/staging.nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/staging.nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/staging.nextcloud.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/staging.nextcloud.com\/it\/#\/schema\/person\/8b00c7d4313f1ecb465e6785204ffb4b","name":"Mikaela Schneider","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b0e9ca5948ab0ab4c0732dd1e79442d7b531e574a27757a9fbc4fad5f732b0f?s=96&d=mm&r=g","caption":"Mikaela Schneider"}}]}},"featured_media_url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/02\/AIO-Linux.png","_links":{"self":[{"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/95470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/comments?post=95470"}],"version-history":[{"count":2,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/95470\/revisions"}],"predecessor-version":[{"id":97421,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/posts\/95470\/revisions\/97421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/media\/94584"}],"wp:attachment":[{"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/media?parent=95470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/categories?post=95470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.nextcloud.com\/it\/wp-json\/wp\/v2\/tags?post=95470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}