{"id":101969,"date":"2023-03-03T13:32:18","date_gmt":"2023-03-03T12:32:18","guid":{"rendered":"https:\/\/nextcloud.com\/?p=101969"},"modified":"2023-03-03T13:38:35","modified_gmt":"2023-03-03T12:38:35","slug":"fujitsu-to-showcase-nextcloud-technology-at-didacta","status":"publish","type":"post","link":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/","title":{"rendered":"Fujitsu to Showcase Nextcloud Technology at Didacta"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized-1024x576.png\" alt=\"\" class=\"wp-image-101974\" srcset=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized-1024x576.png 1024w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized-300x169.png 300w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized-768x432.png 768w, https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Our partner, <a href=\"https:\/\/www.fujitsu.com\/de\/\">Fujitsu<\/a>, will be participating in Didacta, the world&#8217;s largest trade fair for education and training, from 7 to 11 March 2023 at Messe Stuttgart.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At this trade fair Fujitsu will be showcasing their Securon Connect education portal, which offers a broad range of services from Identity Management to Messaging and Video Conferencing, and even Moodle Learning Management as a Service. Additionally, Fujitsu will be presenting the use of <a href=\"https:\/\/nextcloud.com\/hub\">Nextcloud Hub<\/a> technology, as part of Securon Connect, which features real-time document editing, chat functionality, and video conferencing, making it the ideal solution for remote learning and collaboration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fujitsu is a reliable service provider and connecting system integrator in the education sector. We encourage you to visit Fujitsu at Didacta and learn how their solutions can transform the way we learn and work together. Their booth located in Hall 1, booth G13.2 as part of the B\u00fcndnis f\u00fcr Bildung (Alliance for Education) booth setup.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To find out more about Didacta, please visit the <a href=\"https:\/\/www.messe-stuttgart.de\/didacta\/\">official website<\/a> and to learn more about Fujitsu and their technologies for schools and universities, please visit their <a href=\"https:\/\/www.fujitsu.com\/de\/microsite\/education\/\">dedicated education page<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fujitsu will present their Securon Connect education portal and Nextcloud Hub technology at Didacta, the world&#8217;s largest trade fair for education and training, from 7 to 11 March 2023 at Messe Stuttgart.<\/p>\n","protected":false},"author":15,"featured_media":101974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[22,18,243],"tags":[],"class_list":["post-101969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-partner","category-uncategorized-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud\" \/>\n<meta property=\"og:description\" content=\"Fujitsu will present their Securon Connect education portal and Nextcloud Hub technology at Didacta, the world&#039;s largest trade fair for education and training, from 7 to 11 March 2023 at Messe Stuttgart.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/\" \/>\n<meta property=\"og:site_name\" content=\"Nextcloud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nextclouders\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T12:32:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T12:38:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fabrice Mous\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nextclouders\" \/>\n<meta name=\"twitter:site\" content=\"@nextclouders\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet af\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabrice Mous\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/\"},\"author\":{\"name\":\"Fabrice Mous\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#\\\/schema\\\/person\\\/a66d0148bd2735ede376eedcee5e0b0b\"},\"headline\":\"Fujitsu to Showcase Nextcloud Technology at Didacta\",\"datePublished\":\"2023-03-03T12:32:18+00:00\",\"dateModified\":\"2023-03-03T12:38:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/\"},\"wordCount\":190,\"publisher\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fuji-at-didacta-featured-optimized.png\",\"articleSection\":[\"Events\",\"partner\",\"Uncategorized\"],\"inLanguage\":\"da-DK\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/\",\"name\":\"Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fuji-at-didacta-featured-optimized.png\",\"datePublished\":\"2023-03-03T12:32:18+00:00\",\"dateModified\":\"2023-03-03T12:38:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fuji-at-didacta-featured-optimized.png\",\"contentUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/fuji-at-didacta-featured-optimized.png\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/blog\\\/fujitsu-to-showcase-nextcloud-technology-at-didacta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fujitsu to Showcase Nextcloud Technology at Didacta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#website\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/\",\"name\":\"Nextcloud\",\"description\":\"Regain control over your data\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#organization\",\"name\":\"Nextcloud\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"contentUrl\":\"https:\\\/\\\/staging.nextcloud.com\\\/c\\\/uploads\\\/2022\\\/10\\\/nextcloud-logo-blue-transparent.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Nextcloud\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nextclouders\\\/\",\"https:\\\/\\\/x.com\\\/nextclouders\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10827569\\\/\",\"https:\\\/\\\/youtube.com\\\/nextcloud\",\"https:\\\/\\\/www.instagram.com\\\/nextclouders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/staging.nextcloud.com\\\/da\\\/#\\\/schema\\\/person\\\/a66d0148bd2735ede376eedcee5e0b0b\",\"name\":\"Fabrice Mous\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g\",\"caption\":\"Fabrice Mous\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"da_DK","og_type":"article","og_title":"Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud","og_description":"Fujitsu will present their Securon Connect education portal and Nextcloud Hub technology at Didacta, the world's largest trade fair for education and training, from 7 to 11 March 2023 at Messe Stuttgart.","og_url":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/","og_site_name":"Nextcloud","article_publisher":"https:\/\/www.facebook.com\/Nextclouders\/","article_published_time":"2023-03-03T12:32:18+00:00","article_modified_time":"2023-03-03T12:38:35+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","type":"image\/png"}],"author":"Fabrice Mous","twitter_card":"summary_large_image","twitter_creator":"@nextclouders","twitter_site":"@nextclouders","twitter_misc":{"Skrevet af":"Fabrice Mous","Estimeret l\u00e6setid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#article","isPartOf":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/"},"author":{"name":"Fabrice Mous","@id":"https:\/\/staging.nextcloud.com\/da\/#\/schema\/person\/a66d0148bd2735ede376eedcee5e0b0b"},"headline":"Fujitsu to Showcase Nextcloud Technology at Didacta","datePublished":"2023-03-03T12:32:18+00:00","dateModified":"2023-03-03T12:38:35+00:00","mainEntityOfPage":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/"},"wordCount":190,"publisher":{"@id":"https:\/\/staging.nextcloud.com\/da\/#organization"},"image":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","articleSection":["Events","partner","Uncategorized"],"inLanguage":"da-DK"},{"@type":"WebPage","@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/","url":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/","name":"Fujitsu to Showcase Nextcloud Technology at Didacta - Nextcloud","isPartOf":{"@id":"https:\/\/staging.nextcloud.com\/da\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#primaryimage"},"image":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","datePublished":"2023-03-03T12:32:18+00:00","dateModified":"2023-03-03T12:38:35+00:00","breadcrumb":{"@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#primaryimage","url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","contentUrl":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/staging.nextcloud.com\/da\/blog\/fujitsu-to-showcase-nextcloud-technology-at-didacta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.nextcloud.com\/da\/"},{"@type":"ListItem","position":2,"name":"Fujitsu to Showcase Nextcloud Technology at Didacta"}]},{"@type":"WebSite","@id":"https:\/\/staging.nextcloud.com\/da\/#website","url":"https:\/\/staging.nextcloud.com\/da\/","name":"Nextcloud","description":"Regain control over your data","publisher":{"@id":"https:\/\/staging.nextcloud.com\/da\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.nextcloud.com\/da\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/staging.nextcloud.com\/da\/#organization","name":"Nextcloud","url":"https:\/\/staging.nextcloud.com\/da\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/staging.nextcloud.com\/da\/#\/schema\/logo\/image\/","url":"https:\/\/staging.nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","contentUrl":"https:\/\/staging.nextcloud.com\/c\/uploads\/2022\/10\/nextcloud-logo-blue-transparent.svg","width":"1024","height":"1024","caption":"Nextcloud"},"image":{"@id":"https:\/\/staging.nextcloud.com\/da\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nextclouders\/","https:\/\/x.com\/nextclouders","https:\/\/www.linkedin.com\/company\/10827569\/","https:\/\/youtube.com\/nextcloud","https:\/\/www.instagram.com\/nextclouders\/"]},{"@type":"Person","@id":"https:\/\/staging.nextcloud.com\/da\/#\/schema\/person\/a66d0148bd2735ede376eedcee5e0b0b","name":"Fabrice Mous","image":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5841f47c282a7e515f59591ffd05005a9a0aa5a40e05b84643f9e0a600a63575?s=96&d=mm&r=g","caption":"Fabrice Mous"}}]}},"featured_media_url":"https:\/\/staging.nextcloud.com\/wp-content\/uploads\/2023\/03\/fuji-at-didacta-featured-optimized.png","_links":{"self":[{"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/posts\/101969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/comments?post=101969"}],"version-history":[{"count":3,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/posts\/101969\/revisions"}],"predecessor-version":[{"id":101979,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/posts\/101969\/revisions\/101979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/media\/101974"}],"wp:attachment":[{"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/media?parent=101969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/categories?post=101969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.nextcloud.com\/da\/wp-json\/wp\/v2\/tags?post=101969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}